{"id":12090,"date":"2024-10-08T04:21:24","date_gmt":"2024-10-08T04:21:24","guid":{"rendered":"https:\/\/blog.seekapa.com\/los-residentes-de-granbury-emprenden-acciones-legales-contra-una-mina-de-criptomonedas-por-contaminacion-acustica\/"},"modified":"2024-10-08T04:21:24","modified_gmt":"2024-10-08T04:21:24","slug":"los-residentes-de-granbury-emprenden-acciones-legales-contra-una-mina-de-criptomonedas-por-contaminacion-acustica","status":"publish","type":"post","link":"https:\/\/blog.seekapa.com\/es\/los-residentes-de-granbury-emprenden-acciones-legales-contra-una-mina-de-criptomonedas-por-contaminacion-acustica\/","title":{"rendered":"Los residentes de Granbury emprenden acciones legales contra una mina de criptomonedas por contaminaci\u00f3n ac\u00fastica"},"content":{"rendered":"<p>Los residentes de Granbury, Texas, se han unido para presentar una demanda contra la empresa de miner\u00eda de criptomonedas Marathon Digital, citando el ruido excesivo de su instalaci\u00f3n de miner\u00eda de Bitcoin cercana. La queja, presentada el 4 de octubre en el Tribunal del Condado de Hood, describe el ruido como una perturbaci\u00f3n considerable que causa un gran malestar a quienes viven en la proximidad del lugar.<\/p>\n<p>Los habitantes locales informan que experimentan una serie de efectos negativos en la salud, incluyendo fatiga, migra\u00f1as y problemas de memoria, derivadas del ruido y las vibraciones continuas asociadas con las operaciones de miner\u00eda. Muchos afirman que sus condiciones m\u00e9dicas existentes, como la hipertensi\u00f3n, han empeorado debido a la incesante perturbaci\u00f3n. La demanda detalla c\u00f3mo los residentes pueden escuchar el ruido y sentir las vibraciones incluso cuando est\u00e1n dentro de sus hogares, afirmando que la situaci\u00f3n ha obstaculizado gravemente su disfrute de sus propiedades.<\/p>\n<p>Adem\u00e1s de los impactos en la salud, la demanda tambi\u00e9n plantea preocupaciones sobre las implicaciones financieras de las actividades mineras. Los residentes alegan que el considerable consumo de energ\u00eda requerido para las operaciones ha llevado a un aumento en las facturas de electricidad y a una disminuci\u00f3n en los valores de las propiedades en la zona. Los residentes afectados, representados por un abogado senior de la organizaci\u00f3n sin fines de lucro Earthjustice, exigen que Marathon tome medidas inmediatas para aliviar la contaminaci\u00f3n ac\u00fastica o cesar las operaciones por completo.<\/p>\n<p>Los demandantes buscan una orden judicial permanente para evitar que la instalaci\u00f3n minera genere ruido inapropiado, as\u00ed como compensaci\u00f3n por da\u00f1os y costos legales. La mina de Bitcoin de Granbury, construida inicialmente en abril de 2022, ha tenido varios cambios de propiedad, con Marathon asumiendo el control en enero. Se informa que la instalaci\u00f3n alberga un considerable n\u00famero de rigs de miner\u00eda, contribuyendo a su supuesta tasa de hashrate de 4.3 ExaHashs por segundo.<\/p>\n<p>Esta demanda refleja acciones recientes tomadas por residentes en otras regiones, como Noruega, donde una operaci\u00f3n minera fue cerrada debido a quejas por ruido. Sin embargo, las consecuencias de tales cierres pueden llevar a un aumento en los costos de electricidad para los residentes locales, destacando el complejo equilibrio entre las operaciones de miner\u00eda de criptomonedas y el bienestar comunitario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Residents of Granbury, Texas, have united to file a lawsuit against the cryptocurrency mining company Marathon Digital,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":12085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[102],"tags":[223,54,100],"class_list":["post-12090","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-noticias-del-mercado-cripto","tag-bitcoin-es","tag-crypto-es","tag-marketnews-es","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"feature_image_url":"https:\/\/bcdn2.seekapa.com\/wp-content\/uploads\/prod-seekapa-blog\/2024\/10\/regulation_11-1.jpg","_links":{"self":[{"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/posts\/12090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/comments?post=12090"}],"version-history":[{"count":0,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/posts\/12090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/media\/12085"}],"wp:attachment":[{"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/media?parent=12090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/categories?post=12090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/tags?post=12090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}