{"id":13072,"date":"2024-10-15T04:20:52","date_gmt":"2024-10-15T04:20:52","guid":{"rendered":"https:\/\/blog.seekapa.com\/australia-lanza-el-primer-etf-de-ether-el-etf-monocromatico-de-ethereum-establece-un-nuevo-estandar\/"},"modified":"2024-10-15T04:20:52","modified_gmt":"2024-10-15T04:20:52","slug":"australia-lanza-el-primer-etf-de-ether-el-etf-monocromatico-de-ethereum-establece-un-nuevo-estandar","status":"publish","type":"post","link":"https:\/\/blog.seekapa.com\/es\/australia-lanza-el-primer-etf-de-ether-el-etf-monocromatico-de-ethereum-establece-un-nuevo-estandar\/","title":{"rendered":"Australia lanza el primer ETF de Ether: el ETF monocrom\u00e1tico de Ethereum establece un nuevo est\u00e1ndar"},"content":{"rendered":"<p>Monochrome Asset Management ha introducido el primer fondo cotizado en bolsa (ETF) de Australia que posee Ether directamente. A partir del 15 de octubre, el Monochrome Ethereum ETF (IETH) comenz\u00f3 a operar en la bolsa de valores Cboe Australia, registrando activos netos totales de AUD 262,500 (aproximadamente $176,600) a las 2:00 PM, hora local.<\/p>\n<p>Este ETF tiene una tarifa de gesti\u00f3n del 0.50% y ofrece la opci\u00f3n de aplicaciones y redenciones en especie, permitiendo transacciones tanto en efectivo como en Ether (ETH). IETH es distintivo por ser el \u00fanico ETF de Ether de acceso dual disponible en Australia. Ha contratado a BitGo y Gemini como sus custodios de criptomonedas, mientras que State Street Australia se encarga de la administraci\u00f3n del fondo.<\/p>\n<p>La presentaci\u00f3n de IETH sigue al lanzamiento del Bitcoin ETF (IBTC) de Monochrome en junio, que ha logrado reunir casi AUD 16 millones ($10.7 millones) en activos netos. El \u00e9xito anterior del Bitcoin ETF indica una tendencia creciente en la que los clientes est\u00e1n transfiriendo criptomonedas mantenidas en intercambios a veh\u00edculos de inversi\u00f3n estructurados como los ETFs.<\/p>\n<p>El mercado australiano parece bien posicionado para el desempe\u00f1o de los ETFs de criptomonedas al contado, reflejando una trayectoria \u00fanica en comparaci\u00f3n con otros mercados globales. Esto sugiere un potencial significativo para el crecimiento futuro, ya que hay un apetito creciente por estructuras reguladas en la inversi\u00f3n en criptomonedas.<\/p>\n<p>A principios de este a\u00f1o, VanEck tambi\u00e9n lanz\u00f3 el primer ETF de Bitcoin al contado de Australia, que actualmente gestiona alrededor de AUD 52 millones ($35 millones) en activos. En contraste, Estados Unidos lidera la carga global en ETFs de criptomonedas, con un total de 11 fondos de Bitcoin al contado que han recaudado colectivamente $19.3 mil millones en activos bajo gesti\u00f3n solo en 2023. Datos recientes indican que el 14 de octubre se observ\u00f3 un aumento significativo en las entradas de ETFs, registr\u00e1ndose un total de $556 millones en varios fondos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monochrome Asset Management has introduced Australia&#8217;s inaugural exchange-traded fund (ETF) that directly holds Ether. A&#8230;<\/p>\n","protected":false},"author":2,"featured_media":13067,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[102],"tags":[54,224,100],"class_list":["post-13072","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-noticias-del-mercado-cripto","tag-crypto-es","tag-ethereum-es","tag-marketnews-es","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"feature_image_url":"https:\/\/bcdn2.seekapa.com\/wp-content\/uploads\/prod-seekapa-blog\/2024\/10\/eth_8.jpg","_links":{"self":[{"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/posts\/13072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/comments?post=13072"}],"version-history":[{"count":0,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/posts\/13072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/media\/13067"}],"wp:attachment":[{"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/media?parent=13072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/categories?post=13072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/tags?post=13072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}