{"id":49361,"date":"2026-04-22T13:40:03","date_gmt":"2026-04-22T13:40:03","guid":{"rendered":"https:\/\/blog.seekapa.com\/el-par-nzd-usd-sube-ante-los-solidos-datos-de-inflacion-en-nueva-zelanda\/"},"modified":"2026-04-22T13:40:03","modified_gmt":"2026-04-22T13:40:03","slug":"el-par-nzd-usd-sube-ante-los-solidos-datos-de-inflacion-en-nueva-zelanda","status":"publish","type":"post","link":"https:\/\/blog.seekapa.com\/es\/el-par-nzd-usd-sube-ante-los-solidos-datos-de-inflacion-en-nueva-zelanda\/","title":{"rendered":"El par NZD\/USD sube ante los s\u00f3lidos datos de inflaci\u00f3n en Nueva Zelanda"},"content":{"rendered":"<p>El d\u00f3lar neozeland\u00e9s extendi\u00f3 su avance por segunda sesi\u00f3n consecutiva frente al d\u00f3lar estadounidense este martes, con el par NZD\/USD cotizando cerca de 0.5900, lo que representa un aumento de aproximadamente el 0.20 % en el d\u00eda. El par se ha recuperado del m\u00ednimo del lunes cercano a 0.5850, respaldado principalmente por datos de inflaci\u00f3n nacional m\u00e1s s\u00f3lidos y un tono ligeramente m\u00e1s firme en el sentimiento general del mercado.<\/p>\n<p>El \u00faltimo informe del \u00cdndice de Precios al Consumidor (IPC) de Nueva Zelanda mostr\u00f3 que la inflaci\u00f3n trimestral aument\u00f3 un 0.9 % en el primer trimestre, por encima de las expectativas de un incremento del 0.8 % y m\u00e1s r\u00e1pido que el ritmo del 0.6 % registrado en el trimestre anterior. En t\u00e9rminos anuales, la inflaci\u00f3n se mantuvo en el 3.1 %, tambi\u00e9n por encima de los pron\u00f3sticos, lo que apunta a presiones de precios subyacentes persistentes.<\/p>\n<p>La lectura mantiene la inflaci\u00f3n marginalmente por encima de la banda objetivo del 1.0 % al 3.0 % del Banco de la Reserva de Nueva Zelanda (RBNZ) y ha reforzado las expectativas de que los responsables de la pol\u00edtica econ\u00f3mica necesiten mantener condiciones monetarias restrictivas durante m\u00e1s tiempo. Algunos participantes del mercado asignan ahora una probabilidad significativa a un alza de tasas tan pronto como en la reuni\u00f3n de pol\u00edtica monetaria de mayo, brindando apoyo a corto plazo a la moneda.<\/p>\n<p>Aun as\u00ed, el panorama no est\u00e1 exento de riesgos. Los mayores precios de la energ\u00eda y un trasfondo de crecimiento m\u00e1s d\u00e9bil podr\u00edan generar preocupaciones de estanflaci\u00f3n, limitando la capacidad del \u00abKiwi\u00bb para extender sus ganancias de manera significativa a mediano plazo. Incluso si el banco central adopta una postura m\u00e1s restrictiva (hawkish), esa posici\u00f3n podr\u00eda ofrecer solo un alivio temporal a menos que la actividad econ\u00f3mica se mantenga de manera m\u00e1s convincente.<\/p>\n<p>El sentimiento en los mercados globales ha mejorado modestamente ante las especulaciones de que las conversaciones entre Estados Unidos e Ir\u00e1n podr\u00edan reanudarse. Aunque los detalles siguen siendo inciertos, cualquier alivio en las tensiones geopol\u00edticas tiende a beneficiar a las divisas sensibles al riesgo, como el d\u00f3lar neozeland\u00e9s.<\/p>\n<p>El d\u00f3lar estadounidense se ha mantenido relativamente moderado, con el \u00cdndice del D\u00f3lar (DXY) cerca de 98.30 mientras los inversores eval\u00faan un conjunto mixto de indicadores de EE. UU. Las ventas minoristas de marzo aumentaron un 1.7 % intermensual, superando las expectativas, pero los datos no han sido lo suficientemente s\u00f3lidos como para restaurar un impulso alcista sostenido en la divisa. Al mismo tiempo, los inversores contin\u00faan vigilando los acontecimientos en Oriente Medio, donde las elevadas tensiones y la posibilidad de una escalada militar siguen nublando las perspectivas del mercado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00f3lar neozeland\u00e9s extendi\u00f3 su avance por segunda sesi\u00f3n consecutiva frente al d\u00f3lar estadounidense este martes, con e&#8230;<\/p>\n","protected":false},"author":2,"featured_media":49357,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[99],"tags":[221],"class_list":["post-49361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-mercado-forex","tag-nzd-es"],"acf":[],"aioseo_notices":[],"feature_image_url":"https:\/\/bcdn2.seekapa.com\/wp-content\/uploads\/prod-seekapa-blog\/2026\/04\/nzd_usd_3.jpg","_links":{"self":[{"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/posts\/49361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/comments?post=49361"}],"version-history":[{"count":0,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/posts\/49361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/media\/49357"}],"wp:attachment":[{"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/media?parent=49361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/categories?post=49361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.seekapa.com\/es\/wp-json\/wp\/v2\/tags?post=49361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}