{"id":15579,"date":"2024-11-01T01:53:40","date_gmt":"2024-11-01T01:53:40","guid":{"rendered":"https:\/\/blog.seekapa.com\/gbp-usd-atinge-o-ponto-mais-baixo-desde-agosto-em-meio-as-preocupacoes-economicas-do-reino-unido\/"},"modified":"2024-11-01T01:53:40","modified_gmt":"2024-11-01T01:53:40","slug":"gbp-usd-atinge-o-ponto-mais-baixo-desde-agosto-em-meio-as-preocupacoes-economicas-do-reino-unido","status":"publish","type":"post","link":"https:\/\/blog.seekapa.com\/pt-br\/gbp-usd-atinge-o-ponto-mais-baixo-desde-agosto-em-meio-as-preocupacoes-economicas-do-reino-unido\/","title":{"rendered":"GBP\/USD atinge o ponto mais baixo desde agosto em meio \u00e0s preocupa\u00e7\u00f5es econ\u00f4micas do Reino Unido"},"content":{"rendered":"<p>O par GBP\/USD iniciou o preg\u00e3o asi\u00e1tico de sexta-feira com uma queda para seu n\u00edvel mais baixo desde meados de agosto, sendo negociado atualmente em torno de 1,2895. O recente an\u00fancio da primeira Declara\u00e7\u00e3o de Previs\u00e3o de Outono do governo trabalhista do Reino Unido pesou sobre a moeda brit\u00e2nica, levantando preocupa\u00e7\u00f5es.<\/p>\n<p>Resultados econ\u00f4micos sobre a infla\u00e7\u00e3o dos EUA indicados pelo \u00cdndice de Pre\u00e7os para Gastos de Consumo Pessoal (PCE), superaram um pouco as expectativas para setembro. Os dados rec\u00e9m-divulgados pelo Escrit\u00f3rio de An\u00e1lises Econ\u00f4micas mostraram que o PCE apresentou um aumento de 2,1% em rela\u00e7\u00e3o ao ano anterior, consistente com as previs\u00f5es do mercado e ligeiramente inferior ao valor de agosto, de 2,2%. Enquanto isso, o n\u00facleo do PCE, que exclui os setores mais vol\u00e1teis de alimentos e energia, subiu 2,7%, igualando o aumento do m\u00eas anterior e superando as expectativas de 2,6%. Os investidores apostam em um poss\u00edvel corte de 25 pontos-base na taxa de juros dos EUA durante as pr\u00f3ximas reuni\u00f5es em novembro e dezembro.<\/p>\n<p>Enquanto isso, o mercado aguarda com aten\u00e7\u00e3o a divulga\u00e7\u00e3o dos dados antecipados das folhas de pagamento n\u00e3o agr\u00edcolas de outubro, que devem ser divulgados ainda hoje. As estimativas apontam que a economia dos EUA criou aproximadamente 113.000 empregos durante o m\u00eas, com a taxa de desemprego prevista para se manter est\u00e1vel em 4,1%.<\/p>\n<p>Do ponto de vista do Reino Unido, o novo governo trabalhista an\u00fancio uma nova medida fiscal que visa arrecadar 40 bilh\u00f5es de libras esterlinas por meio de aumentos de impostos. Essa iniciativa tem como objetivo lidar com os d\u00e9ficits financeiros e refor\u00e7ar os servi\u00e7os p\u00fablicos. Al\u00e9m disso, o Office for Business Responsibility reavaliou as proje\u00e7\u00f5es de infla\u00e7\u00e3o para 2024, prevendo agora um aumento para 2,5%, em compara\u00e7\u00e3o com uma estimativa anterior de 2,2%. Essa revis\u00e3o pode levar os investidores a prever menos cortes nas taxas de juros do Banco da Inglaterra, o que pode fortalecer a libra esterlina no futuro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O par GBP\/USD iniciou o preg\u00e3o asi\u00e1tico de sexta-feira com uma queda para seu n\u00edvel mais baixo desde meados de agosto, s&#8230;<\/p>\n","protected":false},"author":2,"featured_media":15575,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[113],"tags":[127,135,126],"class_list":["post-15579","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-noticias-dos-mercados","tag-forex-pt-br","tag-gbp-usd-pt-br","tag-marketnews-pt-br","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"feature_image_url":"https:\/\/bcdn2.seekapa.com\/wp-content\/uploads\/prod-seekapa-blog\/2024\/11\/united_kingdom_2.jpg","_links":{"self":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts\/15579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/comments?post=15579"}],"version-history":[{"count":0,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts\/15579\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/media\/15575"}],"wp:attachment":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=15579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/categories?post=15579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/tags?post=15579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}