{"id":18340,"date":"2024-11-20T11:06:10","date_gmt":"2024-11-20T11:06:10","guid":{"rendered":"https:\/\/blog.seekapa.com\/bitcoin-puell-se-aproxima-do-cruzamento-de-chaves-um-sinal-de-alta\/"},"modified":"2024-11-20T11:06:10","modified_gmt":"2024-11-20T11:06:10","slug":"bitcoin-puell-se-aproxima-do-cruzamento-de-chaves-um-sinal-de-alta","status":"publish","type":"post","link":"https:\/\/blog.seekapa.com\/pt-br\/bitcoin-puell-se-aproxima-do-cruzamento-de-chaves-um-sinal-de-alta\/","title":{"rendered":"Bitcoin Puell se aproxima do cruzamento de chaves: Um sinal de alta?"},"content":{"rendered":"<p>An\u00e1lises recentes na cadeia indicam que o Bitcoin Puell Multiple est\u00e1 se aproximando de um cruzamento significativo com sua m\u00e9dia m\u00f3vel (MA) de 365 dias, um desenvolvimento que historicamente tem sido associado a movimentos positivos de pre\u00e7os do Bitcoin. O Puell Multiple \u00e9 uma m\u00e9trica on-chain amplamente utilizada que compara a receita das mineradoras com sua m\u00e9dia anual, refletindo a sa\u00fade do setor de minera\u00e7\u00e3o em rela\u00e7\u00e3o aos ganhos hist\u00f3ricos.<\/p>\n<p>Os mineradores geram renda principalmente por meio de taxas de transa\u00e7\u00e3o e subs\u00eddios de bloco; no entanto, o M\u00faltiplo de Puell se concentra apenas no subs\u00eddio de bloco, que \u00e9 a recompensa que os mineradores recebem por adicionar novos blocos ao blockchain. Um valor acima de 1 significa que os mineradores est\u00e3o ganhando mais do que sua m\u00e9dia hist\u00f3rica, enquanto um valor abaixo de 1 indica uma receita menor em rela\u00e7\u00e3o ao desempenho do ano anterior.<\/p>\n<p>No in\u00edcio deste ano, o Puell Multiple caiu abaixo do limite cr\u00edtico de 1, mas recentemente apresentou um movimento ascendente significativo. Essa queda foi atribu\u00edda em grande parte ao mais recente evento de redu\u00e7\u00e3o do Bitcoin pela metade, que ocorre aproximadamente a cada quatro anos e reduz pela metade o subs\u00eddio de bloco concedido aos mineradores. Como o Puell Multiple rastreia o valor desse subs\u00eddio, sua flutua\u00e7\u00e3o \u00e9 naturalmente afetada por esses eventos de redu\u00e7\u00e3o pela metade. Em outras ocasi\u00f5es, o m\u00faltiplo tamb\u00e9m pode mudar com base no valor em d\u00f3lares americanos das recompensas de minera\u00e7\u00e3o, que s\u00e3o pagas em Bitcoin.<\/p>\n<p>Atualmente, o Bitcoin est\u00e1 em torno da marca de US$ 91.900 e est\u00e1 passando por um per\u00edodo de relativa estabilidade ap\u00f3s os recentes aumentos de pre\u00e7o. A proximidade do Puell Multiple com sua MA de 365 dias levanta a quest\u00e3o de saber se ele ultrapassar\u00e1 esse n\u00edvel, o que poderia sinalizar uma poss\u00edvel tend\u00eancia de alta. As tend\u00eancias hist\u00f3ricas sugerem que, quando esse cruzamento ocorre, os pre\u00e7os do Bitcoin se recuperam significativamente, sugerindo que os traders podem estar monitorando de perto esse indicador para poss\u00edveis sinais de alta no futuro pr\u00f3ximo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>An\u00e1lises recentes na cadeia indicam que o Bitcoin Puell Multiple est\u00e1 se aproximando de um cruzamento significativo com&#8230;<\/p>\n","protected":false},"author":2,"featured_media":18336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[110],"tags":[133,388,390],"class_list":["post-18340","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-analise-tecnica-de-criptomoedas","tag-bitcoin-pt-br","tag-crypto-pt-br","tag-technicalanalysis-pt-br","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"feature_image_url":"https:\/\/bcdn2.seekapa.com\/wp-content\/uploads\/prod-seekapa-blog\/2024\/11\/btc_41-3.jpg","_links":{"self":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts\/18340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/comments?post=18340"}],"version-history":[{"count":0,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts\/18340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/media\/18336"}],"wp:attachment":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=18340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/categories?post=18340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/tags?post=18340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}