{"id":24563,"date":"2025-01-06T14:39:54","date_gmt":"2025-01-06T14:39:54","guid":{"rendered":"https:\/\/blog.seekapa.com\/microstrategy-adquire-1-070-btc-por-us-101-milhoes-em-um-movimento-estrategico\/"},"modified":"2025-01-06T14:39:54","modified_gmt":"2025-01-06T14:39:54","slug":"microstrategy-adquire-1-070-btc-por-us-101-milhoes-em-um-movimento-estrategico","status":"publish","type":"post","link":"https:\/\/blog.seekapa.com\/pt-br\/microstrategy-adquire-1-070-btc-por-us-101-milhoes-em-um-movimento-estrategico\/","title":{"rendered":"MicroStrategy adquire 1.070 BTC por US$ 101 milh\u00f5es em um movimento estrat\u00e9gico"},"content":{"rendered":"<p>A MicroStrategy, um not\u00e1vel participante corporativo no mercado de Bitcoin, anunciou a aquisi\u00e7\u00e3o de mais 1.070 BTC nos \u00faltimos dias de 2024. Essa compra foi confirmada pela empresa atrav\u00e9s de um registro em 6 de janeiro, revelando um gasto em torno de US$ 101 milh\u00f5es em dinheiro em 30 e 31 de dezembro de 2024.<\/p>\n<p>De acordo com a divulga\u00e7\u00e3o da Comiss\u00e3o de Valores Mobili\u00e1rios dos EUA, a MicroStrategy adquiriu essas unidades de Bitcoin por um pre\u00e7o m\u00e9dio de aproximadamente US$ 94.004 cada. A empresa n\u00e3o realizou novas compras de Bitcoin desde o final de dezembro, conforme revelado no \u00faltimo registro do Formul\u00e1rio 8-K.<\/p>\n<p>Esta \u00faltima aquisi\u00e7\u00e3o segue um padr\u00e3o estabelecido pela MicroStrategy de utilizar os recursos provenientes de emiss\u00f5es de a\u00e7\u00f5es para aumentar sua exposi\u00e7\u00e3o \u00e0 Bitcoin. Anteriormente, a estrat\u00e9gia consistia em utilizar os fundos obtidos com a venda de notas convers\u00edveis para realizar investimentos adicionais em BTC. O cofundador da empresa sugeriu uma prov\u00e1vel aquisi\u00e7\u00e3o atrav\u00e9s de insights do site SaylorTracker em 5 de janeiro, pouco antes da realiza\u00e7\u00e3o da nova compra.<\/p>\n<p>O cont\u00ednuo ac\u00famulo de Bitcoin pela MicroStrategy a posiciona como uma empresa que tem o compromisso de incluir ativos digitais como parte de sua estrat\u00e9gia financeira corporativa. Diante da evolu\u00e7\u00e3o desse cen\u00e1rio, mais detalhes sobre os futuros empreendimentos da MicroStrategy e os impactos no mercado de criptomoedas em geral surgir\u00e3o ao longo do caminho.<\/p>\n<p>A magnitude dos investimentos da MicroStrategy em Bitcoin a transforma em um importante influenciador do mercado. Suas decis\u00f5es geram precedentes para outras corpora\u00e7\u00f5es que buscam caminhos similares \u00e0 medida que o cen\u00e1rio de investimentos em criptomoedas evolui.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A MicroStrategy, um not\u00e1vel participante corporativo no mercado de Bitcoin, anunciou a aquisi\u00e7\u00e3o de mais 1.070 BTC nos \u00fa&#8230;<\/p>\n","protected":false},"author":2,"featured_media":24559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[109],"tags":[133,388,126],"class_list":["post-24563","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-noticias-do-mercado-cripto","tag-bitcoin-pt-br","tag-crypto-pt-br","tag-marketnews-pt-br","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"feature_image_url":"https:\/\/bcdn2.seekapa.com\/wp-content\/uploads\/prod-seekapa-blog\/2025\/01\/usa_38.jpg","_links":{"self":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts\/24563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/comments?post=24563"}],"version-history":[{"count":0,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts\/24563\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/media\/24559"}],"wp:attachment":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=24563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/categories?post=24563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/tags?post=24563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}