{"id":26120,"date":"2025-01-16T12:21:20","date_gmt":"2025-01-16T12:21:20","guid":{"rendered":"https:\/\/blog.seekapa.com\/aud-enfraquece-apesar-dos-fortes-dados-de-emprego-com-o-aumento-das-especulacoes-sobre-o-corte-da-taxa-do-rba\/"},"modified":"2025-01-16T12:21:20","modified_gmt":"2025-01-16T12:21:20","slug":"aud-enfraquece-apesar-dos-fortes-dados-de-emprego-com-o-aumento-das-especulacoes-sobre-o-corte-da-taxa-do-rba","status":"publish","type":"post","link":"https:\/\/blog.seekapa.com\/pt-br\/aud-enfraquece-apesar-dos-fortes-dados-de-emprego-com-o-aumento-das-especulacoes-sobre-o-corte-da-taxa-do-rba\/","title":{"rendered":"AUD enfraquece apesar dos fortes dados de emprego, com o aumento das especula\u00e7\u00f5es sobre o corte da taxa do RBA"},"content":{"rendered":"<p>O d\u00f3lar australiano (AUD) registrou uma queda em rela\u00e7\u00e3o ao d\u00f3lar americano (USD), quebrando a sequ\u00eancia de tr\u00eas dias de alta que o levou a superar o n\u00edvel de resist\u00eancia importante em 0,6245 durante o preg\u00e3o europeu de quinta-feira. O decl\u00ednio aconteceu mesmo com a divulga\u00e7\u00e3o de dados do mercado de trabalho da Austr\u00e1lia positivos para dezembro.<\/p>\n<p>O Australian Bureau of Statistics (ABS) revelou que houve a cria\u00e7\u00e3o de 53.600 empregos em dezembro, superando significativamente o n\u00famero do m\u00eas anterior de 28.200 e proje\u00e7\u00f5es de apenas 15.000 novos empregos. Ao mesmo tempo, a taxa de desemprego aumentou de 3,9% em novembro para 4,0%, seguindo as estimativas do mercado. De modo geral, indicadores mais fortes do mercado de trabalho podem impedir qualquer tend\u00eancia dovish do Reserve Bank of Australia (RBA), que atualmente est\u00e1 observando um aumento na especula\u00e7\u00e3o sobre uma poss\u00edvel redu\u00e7\u00e3o na taxa de juros.<\/p>\n<p>Atualmente, um corte nas taxas de juros pelo RBA est\u00e1 sendo analisado pelos participantes do mercado, com percep\u00e7\u00f5es indicando uma probabilidade de 67% de que a taxa diminua 25 pontos-base para 4,10% em fevereiro, seguida por outra redu\u00e7\u00e3o em abril.<\/p>\n<p>Do outro lado do Pac\u00edfico, o d\u00f3lar americano se mant\u00e9m est\u00e1vel, \u00e0 medida que os investidores aguardam a divulga\u00e7\u00e3o dos principais dados econ\u00f4micos, incluindo os n\u00fameros dos pedidos iniciais de aux\u00edlio-desemprego e das vendas no varejo de dezembro. A partir de agora, espera-se um aumento para 210.000 pedidos de aux\u00edlio-desemprego pela primeira vez, ante os 201.000 relatados anteriormente. Al\u00e9m disso, quanto \u00e0s vendas no varejo, um indicador importante dos gastos dos consumidores, projeta-se um crescimento de 0,6%, abaixo dos 0,7% do m\u00eas anterior.<\/p>\n<p>O pr\u00f3ximo relat\u00f3rio de vendas no varejo assume uma import\u00e2ncia crucial, pois seus resultados moldar\u00e3o as expectativas do mercado sobre a futura pol\u00edtica monet\u00e1ria do Federal Reserve. Atualmente, h\u00e1 uma especula\u00e7\u00e3o dos traders de um corte de 25 pontos-base na taxa de juros at\u00e9 junho pelo Federal Reserve.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O d\u00f3lar australiano (AUD) registrou uma queda em rela\u00e7\u00e3o ao d\u00f3lar americano (USD), quebrando a sequ\u00eancia de tr\u00eas dias de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":26116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[113],"tags":[193,127,126],"class_list":["post-26120","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-noticias-dos-mercados","tag-dolar-pt-br","tag-forex-pt-br","tag-marketnews-pt-br","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"feature_image_url":"https:\/\/bcdn2.seekapa.com\/wp-content\/uploads\/prod-seekapa-blog\/2025\/01\/usd_21.jpg","_links":{"self":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts\/26120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/comments?post=26120"}],"version-history":[{"count":0,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts\/26120\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/media\/26116"}],"wp:attachment":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=26120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/categories?post=26120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/tags?post=26120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}