{"id":26818,"date":"2025-01-21T18:55:46","date_gmt":"2025-01-21T18:55:46","guid":{"rendered":"https:\/\/blog.seekapa.com\/recuo-do-peso-reacoes-do-mercado-as-ameacas-tarifarias-de-trump-e-perspectivas-economicas\/"},"modified":"2025-01-21T18:55:46","modified_gmt":"2025-01-21T18:55:46","slug":"recuo-do-peso-reacoes-do-mercado-as-ameacas-tarifarias-de-trump-e-perspectivas-economicas","status":"publish","type":"post","link":"https:\/\/blog.seekapa.com\/pt-br\/recuo-do-peso-reacoes-do-mercado-as-ameacas-tarifarias-de-trump-e-perspectivas-economicas\/","title":{"rendered":"Recuo do peso: rea\u00e7\u00f5es do mercado \u00e0s amea\u00e7as tarif\u00e1rias de Trump e perspectivas econ\u00f4micas"},"content":{"rendered":"<p>Ap\u00f3s um ganho inicial na sess\u00e3o do dia da posse do presidente dos EUA, Donald Trump, o peso mexicano sofreu uma retra\u00e7\u00e3o. O par USD\/MXN alcan\u00e7ou o n\u00edvel de 20,79, antes de se estabilizar em torno de 20,59, representando um aumento de 0,60%, depois da declara\u00e7\u00e3o de Trump sobre poss\u00edveis tarifas de 25% sobre o M\u00e9xico e o Canad\u00e1. O debate sobre tarifas resultou em uma queda de v\u00e1rias moedas vizinhas em rela\u00e7\u00e3o ao d\u00f3lar americano. Entretanto, no decorrer da sess\u00e3o, o peso apresentou sinais de recupera\u00e7\u00e3o, com a diminui\u00e7\u00e3o das preocupa\u00e7\u00f5es de um impacto econ\u00f4mico imediato.<\/p>\n<p>A presidente mexicana, Claudia Sheinbaum, expressou o comprometimento em proteger a soberania do pa\u00eds e, ao mesmo tempo, defendendo o di\u00e1logo com os EUA, o que intensificou as tens\u00f5es entre as na\u00e7\u00f5es. Apesar das preocupa\u00e7\u00f5es econ\u00f4micas, o setor varejista do M\u00e9xico demonstrou certa resist\u00eancia, com uma contra\u00e7\u00e3o menor do que o esperado nas vendas no varejo de novembro. No \u00e2mbito anual, os dados indicam um decl\u00ednio, gerando preocupa\u00e7\u00f5es sobre as tend\u00eancias de gastos dos consumidores em meio \u00e0s press\u00f5es econ\u00f4micas.<\/p>\n<p>O calend\u00e1rio econ\u00f4mico dos pr\u00f3ximos dias ser\u00e1 marcado pela divulga\u00e7\u00e3o de indicadores econ\u00f4micos importantes, incluindo os dados de infla\u00e7\u00e3o do meio do m\u00eas de janeiro e o Indicador de Atividade Econ\u00f4mica de novembro. Nos EUA, os pr\u00f3ximos relat\u00f3rios sobre os pedidos iniciais de aux\u00edlio-desemprego e os PMIs Flash trar\u00e3o mais pistas sobre o cen\u00e1rio econ\u00f4mico.<\/p>\n<p>Na ter\u00e7a-feira, as declara\u00e7\u00f5es de Trump sobre as tarifas impactaram diretamente as oscila\u00e7\u00f5es do peso. As vendas no varejo apresentaram uma contra\u00e7\u00e3o de 0,1% em rela\u00e7\u00e3o ao m\u00eas anterior em novembro, um resultado ligeiramente melhor do que o esperado de uma queda de 0,3%. Os n\u00fameros das vendas anuais registraram uma queda de 1,9%, que foi pior do que as proje\u00e7\u00f5es de um decl\u00ednio de 1,2%.<\/p>\n<p>Os coment\u00e1rios do vice-governador do Banxico sinalizaram uma postura cautelosa para a infla\u00e7\u00e3o, com proje\u00e7\u00f5es de que a infla\u00e7\u00e3o e o n\u00facleo de infla\u00e7\u00e3o possam chegar a 4% em janeiro. Essa perspectiva dovish sugere uma menor inclina\u00e7\u00e3o do Banxico para adotar uma pol\u00edtica monet\u00e1ria excessivamente restritiva. De acordo com os economistas, o Banxico poder\u00e1 realizar cortes de at\u00e9 150 pontos-base nas taxas de juros at\u00e9 o final do ano, contrastando com as expectativas de cortes de 50 pontos-base pelo Federal Reserve.<\/p>\n<p>Em termos de an\u00e1lise t\u00e9cnica, a incerteza entre os participantes do mercado influenciou as negocia\u00e7\u00f5es do par USD\/MXN, que oscilou entre 20,50 e 20,90 nas \u00faltimas sess\u00f5es. Caso a tend\u00eancia de alta da taxa de c\u00e2mbio permane\u00e7a, ela poder\u00e1 testar o n\u00edvel de resist\u00eancia importante pr\u00f3ximo a 21,00. Por outro lado, uma queda abaixo da m\u00e9dia m\u00f3vel simples de 50 dias pode desencadear um decl\u00ednio maior at\u00e9 a MMS de 100 dias e, potencialmente, abaixo do n\u00edvel significativo de 20,00.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s um ganho inicial na sess\u00e3o do dia da posse do presidente dos EUA, Donald Trump, o peso mexicano sofreu uma retra\u00e7\u00e3o&#8230;<\/p>\n","protected":false},"author":2,"featured_media":26814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[113],"tags":[127,126,498],"class_list":["post-26818","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-noticias-dos-mercados","tag-forex-pt-br","tag-marketnews-pt-br","tag-peso-pt-br","post_format-post-format-image"],"acf":[],"aioseo_notices":[],"feature_image_url":"https:\/\/bcdn2.seekapa.com\/wp-content\/uploads\/prod-seekapa-blog\/2025\/01\/cad_9-3.jpg","_links":{"self":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts\/26818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/comments?post=26818"}],"version-history":[{"count":0,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/posts\/26818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/media\/26814"}],"wp:attachment":[{"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=26818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/categories?post=26818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.seekapa.com\/pt-br\/wp-json\/wp\/v2\/tags?post=26818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}